{"id":741,"date":"2015-08-25T10:32:29","date_gmt":"2015-08-25T08:32:29","guid":{"rendered":"https:\/\/www.polyas.de\/blog\/?p=741"},"modified":"2024-06-21T09:15:08","modified_gmt":"2024-06-21T07:15:08","slug":"flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","status":"publish","type":"post","link":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","title":{"rendered":"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium"},"content":{"rendered":"<p>Die ersten freien Wahlen Deutschlands fanden\u00a01807 in Kassel statt. Nunmehr 200 Jahre sp\u00e4ter geht erneut eine demokratische Revolution aus dem hessischen St\u00e4dtchen aus: FlexiVote \u2013 das individuell konfigurierbare Online-Wahlsystem.<\/p>\n<p><!--more-->Gemeinsam mit der Technischen Universit\u00e4t Darmstadt und dem Software-Entwickler Micromata nimmt POLYAS mit diesem Projekt am LOEWE-F\u00f6rderprogramm der hessischen Landesregierung teil. Ralf M\u00fcller, CEO\u00a0der POLYAS\u00a0GmbH, wird den Stand der Forschungen am 25. August 2015 dem hessischen Staatsminister Axel Wintermeyer in Wiesbaden vorstellen.<\/p>\n<p><strong>Jeder Wahltyp braucht ein spezifisches Online-Wahlsystem<\/strong><\/p>\n<p>Die Entwicklung eines flexiblen Online-Wahlsystems ist notwendig, da unterschiedliche Wahltypen unterschiedliche Anforderungen an Online-Wahlsoftware stellen. So stehen bei einigen Wahlen hohe Sicherheitsanforderungen im Vordergrund, sodass beispielsweise aufw\u00e4ndige kryptografische Komponenten zum Einsatz kommen m\u00fcssen. Weitere Anforderungen k\u00f6nnen aber auch unterschiedliche Stimmzettelformen, Wahlkan\u00e4le und verf\u00fcgbare Authentifizierungsverfahren (z.B. PIN\/TAN oder elektronischer Personalausweis) sein, die sich je nach Wahltyp unterscheiden.<\/p>\n<p>Da bislang f\u00fcr jede unterschiedliche Wahl ein anderes System ausgew\u00e4hlt werden m\u00fcsste, vereinfacht FlexiVote hier die Produktauswahl, indem ein einziges System individuell\u00a0konfiguriert werden kann. Das passende Online-Wahlsystem kann also schnell, einfach und kosteng\u00fcnstig realisiert werden, ohne dass f\u00fcr jedes Wahlsetting ein neues Internetwahlsystem entwickelt werden muss.<\/p>\n<p><strong>Forschungsprojekt im hessischen F\u00f6rderprogramm LOEWE<\/strong><\/p>\n<p><a href=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo.jpg\"><img data-attachment-id=\"755\" data-permalink=\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\/attachment\/loewe_4c_logo\" data-orig-file=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo.jpg\" data-orig-size=\"480,192\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"loewe_4c_logo\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo-300x120.jpg\" data-large-file=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo.jpg\" loading=\"lazy\" class=\" size-medium wp-image-755 alignright\" src=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo-300x120.jpg\" alt=\"loewe_4c_logo\" width=\"300\" height=\"120\" srcset=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo-300x120.jpg 300w, https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/loewe_4c_logo.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Das Projekt (HA-Projekt 435\/14-25) wird im Rahmen von Hessen ModellProjekte aus Mitteln der LOEWE \u2013Landes-Offensive zur Entwicklung Wissenschaftlich-\u00f6konomischer Exzellenz, F\u00f6rderlinie 3: KMU-Verbundvorhaben gef\u00f6rdert.<\/p>\n<p>Das Projekt FlexiVote der TU Darmstadt, Micromata und POLYAS ist auf 24 Monate angelegt und wird noch bis voraussichtlich November 2016 laufen. In mehreren Arbeitsschritten werden die ben\u00f6tigten Module identifiziert, charakterisiert und im Entscheidungssystem umgesetzt sowie getestet. Am Ende des Projektes wird ein FlexiVote Demonstrator entstehen, der praktisch angewendet und getestet werden kann. Geleitet wird das Projekt von Moritz Strube (Technischer Leiter, POLYAS GmbH) und Prof. Dr. Melanie Volkamer (TU Darmstadt).<\/p>\n<p><a href=\"http:\/\/www.rheinmaintv.de\/video\/Axel-Wintermeyer-besucht-LOEWE-Projekt-in-Darmstadt\/b62d30ed86b45cd1fd13e7cb6b27cacb#\" target=\"_blank\" rel=\"noopener\">Das Video zum Besuch des Hessischen Staatsministers Wintermeyer k\u00f6nnen Sie bei rheinmainTV sehen<\/a><\/p>\n<p><a href=\"https:\/\/www.hessen.de\/presse\/pressemitteilung\/staatsminister-wintermeyer-besucht-das-projekt-flexivote-darmstadt\" target=\"_blank\" rel=\"noopener\">Hier gelangen Sie zur Presseinformation des Landes Hessen zum Forschungsprojekt FlexiVote<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ersten freien Wahlen Deutschlands fanden\u00a01807 in Kassel statt. Nunmehr 200 Jahre sp\u00e4ter geht erneut eine demokratische Revolution aus dem hessischen St\u00e4dtchen aus: FlexiVote \u2013 das individuell konfigurierbare Online-Wahlsystem.<\/p>\n","protected":false},"author":1,"featured_media":3403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ub_ctt_via":"","spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[11],"tags":[217,221,215,219],"featured_image_src":"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/flexivote_wintermeyer_polyas.jpg","author_info":{"display_name":"Anna-Maria Palzkill","author_link":"https:\/\/www.polyas.de\/blog\/author\/a-palzkillpolyas-de"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS\" \/>\n<meta property=\"og:description\" content=\"Die ersten freien Wahlen Deutschlands fanden\u00a01807 in Kassel statt. Nunmehr 200 Jahre sp\u00e4ter geht erneut eine demokratische Revolution aus dem hessischen St\u00e4dtchen aus: FlexiVote \u2013 das individuell konfigurierbare Online-Wahlsystem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\" \/>\n<meta property=\"og:site_name\" content=\"POLYAS\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T08:32:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T07:15:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/flexivote_wintermeyer_polyas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Palzkill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@annalysiss\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Palzkill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\",\"url\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\",\"name\":\"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS\",\"isPartOf\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/#website\"},\"datePublished\":\"2015-08-25T08:32:29+00:00\",\"dateModified\":\"2024-06-21T07:15:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/7f0c634cd9f361b087084cd0c9dd52ac\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.polyas.de\/blog\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#website\",\"url\":\"https:\/\/www.polyas.de\/blog\/\",\"name\":\"POLYAS\",\"description\":\"the blog for secure online voting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.polyas.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/7f0c634cd9f361b087084cd0c9dd52ac\",\"name\":\"Anna-Maria Palzkill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14fc41d5721e074dbbb080b61a20bc3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14fc41d5721e074dbbb080b61a20bc3b?s=96&d=mm&r=g\",\"caption\":\"Anna-Maria Palzkill\"},\"description\":\"Als Kommunikationswissenschaftlerin interessiere ich mich f\u00fcr den Einfluss von Technik auf das Leben zwischen Politik und Wirtschaft. Ich m\u00f6chte kleinen Zwischent\u00f6nen auf die Spur kommen und schrecke nicht vor gro\u00dfen Worten zur\u00fcck.\",\"sameAs\":[\"https:\/\/www.polyas.de\",\"https:\/\/twitter.com\/annalysiss\"],\"url\":\"https:\/\/www.polyas.de\/blog\/author\/a-palzkillpolyas-de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","og_locale":"de_DE","og_type":"article","og_title":"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS","og_description":"Die ersten freien Wahlen Deutschlands fanden\u00a01807 in Kassel statt. Nunmehr 200 Jahre sp\u00e4ter geht erneut eine demokratische Revolution aus dem hessischen St\u00e4dtchen aus: FlexiVote \u2013 das individuell konfigurierbare Online-Wahlsystem.","og_url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","og_site_name":"POLYAS","article_published_time":"2015-08-25T08:32:29+00:00","article_modified_time":"2024-06-21T07:15:08+00:00","og_image":[{"width":860,"height":360,"url":"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/flexivote_wintermeyer_polyas.jpg","type":"image\/jpeg"}],"author":"Anna-Maria Palzkill","twitter_card":"summary_large_image","twitter_creator":"@annalysiss","twitter_misc":{"Verfasst von":"Anna-Maria Palzkill","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer","name":"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium - POLYAS","isPartOf":{"@id":"https:\/\/www.polyas.de\/blog\/#website"},"datePublished":"2015-08-25T08:32:29+00:00","dateModified":"2024-06-21T07:15:08+00:00","author":{"@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/7f0c634cd9f361b087084cd0c9dd52ac"},"breadcrumb":{"@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote-polyas-praesentiert-mit-micromata-und-tu-darmstadt-das-loewe-forschungsprojekt-dem-hessischen-staatsminister-wintermeyer#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.polyas.de\/blog\/de"},{"@type":"ListItem","position":2,"name":"FlexiVote: POLYAS pr\u00e4sentiert Forschungsprojekt im hessischen Staatsministerium"}]},{"@type":"WebSite","@id":"https:\/\/www.polyas.de\/blog\/#website","url":"https:\/\/www.polyas.de\/blog\/","name":"POLYAS","description":"the blog for secure online voting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polyas.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/7f0c634cd9f361b087084cd0c9dd52ac","name":"Anna-Maria Palzkill","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14fc41d5721e074dbbb080b61a20bc3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14fc41d5721e074dbbb080b61a20bc3b?s=96&d=mm&r=g","caption":"Anna-Maria Palzkill"},"description":"Als Kommunikationswissenschaftlerin interessiere ich mich f\u00fcr den Einfluss von Technik auf das Leben zwischen Politik und Wirtschaft. Ich m\u00f6chte kleinen Zwischent\u00f6nen auf die Spur kommen und schrecke nicht vor gro\u00dfen Worten zur\u00fcck.","sameAs":["https:\/\/www.polyas.de","https:\/\/twitter.com\/annalysiss"],"url":"https:\/\/www.polyas.de\/blog\/author\/a-palzkillpolyas-de"}]}},"jetpack_featured_media_url":"https:\/\/www.polyas.de\/blog\/wp-content\/uploads\/2015\/08\/flexivote_wintermeyer_polyas.jpg","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p72Pnr-bX","jetpack-related-posts":[{"id":4973,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/forschung\/flexivote","url_meta":{"origin":741,"position":0},"title":"FlexiVote: Forschungsprojekt erfolgreich abgeschlossen","date":"17\/05\/2017","format":false,"excerpt":"2015 startete POLYAS das Forschungsprojekt FlexiVote, gemeinsam mit der Micromata GmbH und der TU Darmstadt. Es ging darum, ein digitales Baukasten-System f\u00fcr demokratische Wahlen aufzubauen. Das Projekt wurde Ende 2016 zu einem erfolgreichen Abschluss gef\u00fchrt. FlexiVote: Ein neues Wahlsystem Die Online-Wahl birgt gro\u00dfe Vorteile. Wahlausrichter k\u00f6nnen auf lange Sicht Kosten\u2026","rel":"","context":"In &quot;Online-Wahlforschung&quot;","img":{"alt_text":"Das Forschungsprojekt FlexiVote","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2017\/05\/PS-cut-Photo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6457,"url":"https:\/\/www.polyas.de\/blog\/de\/digitale-demokratie\/hessen-digitalisierung","url_meta":{"origin":741,"position":1},"title":"Hessen: digitale Innovation aus der Mitte Deutschlands","date":"20\/03\/2018","format":false,"excerpt":"Hessen ist das innovativste Bundesland in Sachen Digitalisierung. In unserer Blogserie \u201eHessen goes digital\u201c stellen wir das Bundesland zwischen Kassel, Frankfurt und Darmstadt und seine Pl\u00e4ne zur Digitalisierung n\u00e4her vor. Das POLYAS-Gr\u00fcndungsbundesland ist auf vielen Ebenen Vorreiter der Digitalisierung. Die Hessische Landesregierung hat hierf\u00fcr sogar die Initiative \u201eDigitales Hessen\u201c ins\u2026","rel":"","context":"In &quot;Digitale Demokratie&quot;","img":{"alt_text":"Welche Projekte gibt es in Deutschland aktuelle zum Thema Digitalisierung und warum ist Hessen das Vorreiter-Bundesland auf diesem Gebiet? Erfahren Sie es in unserer Blogserie","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2016\/03\/Polyas-Serie_Digitalisierung.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6789,"url":"https:\/\/www.polyas.de\/blog\/de\/veranstaltungen\/e-vote-id-2018","url_meta":{"origin":741,"position":2},"title":"POLYAS auf der E-Vote-ID 2018: N\u00fctzt Blockchain der Online-Wahl?","date":"01\/10\/2018","format":false,"excerpt":"Auch in diesem Jahr ist POLYAS wieder bei der E-Vote-ID zu Gast. Nach dem Hype um den Bitcoin im Winter 2017\/18 wird die Blockchain eines der zentralen Themen auf der Konferenz f\u00fcr Online-Wahlen sein. Auch POLYAS bringt sich mit eigenen Erfahrungen ein. Die Blockchain ist wichtiges Thema auf E-Vote-ID Inzwischen\u2026","rel":"","context":"In &quot;Veranstaltungen&quot;","img":{"alt_text":"POLYAS diskutiert auf der E-Vote-ID 2018 \u00fcber den Nutzen der Blockchain f\u00fcr die Online-Wahl","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2018\/09\/block-chain-3047153_1920.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6372,"url":"https:\/\/www.polyas.de\/blog\/de\/digital-news\/digitalisierung-vergleich-bundeslaender","url_meta":{"origin":741,"position":3},"title":"Digitalisierung: 16 Wege in die Zukunft &#8211; Digitalvergleich der Bundesl\u00e4nder","date":"28\/02\/2018","format":false,"excerpt":"Ob Bundestag, Landtag, Senat oder B\u00fcrgermeister: Alle reden von der Digitalisierung, wie wichtig sie sei und dass man sie \u201evorantreiben\u201c m\u00fcsse. Aber was hei\u00dft das eigentlich genau? Wir haben uns die Digitalagenda der einzelnen Bundesl\u00e4nder mal genauer angesehen. Digitalisierung hat viele Gesichter Eines haben alle Bundesl\u00e4nder, bis auf die Stadtstaaten,\u2026","rel":"","context":"In &quot;Digital News&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2018\/02\/Digitalisierung-in-den-Bundeslaendern.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":34,"url":"https:\/\/www.polyas.de\/blog\/de\/digitale-demokratie\/polyas-unterstuetzt-forschungsprojekt-valid-der-tu-darmstadt","url_meta":{"origin":741,"position":4},"title":"POLYAS unterst\u00fctzt Forschungsprojekt VALID der TU Darmstadt","date":"31\/03\/2015","format":false,"excerpt":"POLYAS unterst\u00fctzt die Forschungsarbeit der Master-Studierenden Karola Marky auf dem Gebiet der Liquid Democracy bei Frau Prof. Dr. Melanie Volkamer an der Technischen Universit\u00e4t Darmstadt. Dazu wurde das gemeinsame Projekt VALID (Verifiable Liquid Democracy) aufgesetzt. Ziel des am 1.4.2015 startenden und auf zwei Jahre angelegten wissenschaftlichen Forschungsprojektes ist es, zun\u00e4chst\u2026","rel":"","context":"In &quot;Digitale Demokratie&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7167,"url":"https:\/\/www.polyas.de\/blog\/de\/allgemein-de\/mbg-h-investiert-in-polyas","url_meta":{"origin":741,"position":5},"title":"Hessen investiert in POLYAS Online-Wahlen","date":"16\/05\/2019","format":false,"excerpt":"Die MBG H Mittelst\u00e4ndische Beteiligungsgesellschaft Hessen und die Hessen Kapital I GmbH investieren in POLYAS. Eine entsprechende F\u00f6rderung wurde in 2018 unterzeichnet. Eine Software f\u00fcr sichere Online-Wahlen, das ist das Kernprodukt von POLYAS. Wir investieren umfangreich in die Forschung, um sichere Wahlverfahren mit umfassenden Verifikationsmethoden zu entwickeln. Denn wir wollen\u2026","rel":"","context":"In &quot;\u00dcber POLYAS&quot;","img":{"alt_text":"Erfahren Sie News \u00fcber das Unternehmen POLYAS","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2017\/10\/Polyas_News.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/741"}],"collection":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/comments?post=741"}],"version-history":[{"count":13,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/741\/revisions"}],"predecessor-version":[{"id":12106,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/741\/revisions\/12106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/media\/3403"}],"wp:attachment":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/categories?post=741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/tags?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}