{"id":3488,"date":"2016-10-17T12:55:03","date_gmt":"2016-10-17T10:55:03","guid":{"rendered":"https:\/\/www.polyas.de\/blog\/?p=3488"},"modified":"2016-10-17T12:55:03","modified_gmt":"2016-10-17T10:55:03","slug":"tschechien-montenegro-wahlen","status":"publish","type":"post","link":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen","title":{"rendered":"Tschechien und Montenegro: Wahlsieger mit Verlusten"},"content":{"rendered":"<p><strong>Immer wieder sonntags<\/strong><strong>\u2026. <\/strong>Diesmal haben die Wahl News einen Schwerpunkt auf Osteuropa. In Tschechien wurde am Wochenende in der zweiten Runde der Senat gew\u00e4hlt. \u00a0In Montenegro hat die Partei des Regierungschefs\u00a0Milo Djukanovic die Parlamentswahl gewonnen, aber die absolute Mehrheit verpasst.<\/p>\n<p><strong><!--more--><\/strong><\/p>\n<h3>Die Geschehnisse im \u00dcberblick:<\/h3>\n<p><strong>Tschechien<\/strong>: Die tschechische Mitte-Links-Regierung bleibt nach der Stichwahl st\u00e4rkste Kraft im Senat &#8211; mit herben Verlusten. Die Wahlbeteiligung lag bei historisch niedrigen 15,4 %.<\/p>\n<p><strong>Montenegro:<\/strong> Die Partei von Regierungschef Milo Djukanovic hat die Wahl mit rund 41 Prozent der Stimmen gewonnen, aber sie ist auf einen Koalitionspartner angewiesen. In Montenegro steht eine schwierige Regierungsbildung bevor.<\/p>\n<h3>Tschechien: Ein erster Stimmungstest<\/h3>\n<p>Die Sozialdemokraten von Ministerpr\u00e4sident Bohuslav Sobotka k\u00f6nnen sich dar\u00fcber freuen, dass sie im Senat nach der Stichwahl st\u00e4rkste Kraft geworden sind. Doch herbe Verluste tr\u00fcben das Bild. Die Partei verlor zehn Sitze, sie konnte nur zwei Wahlkreise holen. Ein \u00dcberraschungserfolg gab es hingegen f\u00fcr den Juniorpartner der Sozialdemokraten &#8211; die christdemokratische KDU-CSL.<\/p>\n<p>Sie holte neun Sitzen und kompensierte so die Verluste von Sobotkas Partei. \u00a0Die Abstimmung galt auch als Stimmungstest vor der Parlamentswahl in einem Jahr.<\/p>\n<p>Die Wahlbeteiligung war mit 15,4% so niedrig wie nie. <a href=\"https:\/\/www.polyas.de\/wahlbeteiligung-steigern\">Erfahren Sie hier, wie sich die Wahlbeteiligung steigern l\u00e4sst.\u00a0<\/a><\/p>\n<p class=\"text small\"><strong>Montenegro: Gewonnen, aber die absolute Mehrheit verfehlt<\/strong><\/p>\n<p class=\"text small\">Die Partei von Regierungschef Djukanovic ist st\u00e4rkste Kraft geworden: Sie gewann rund 41% der Stimmen. Damit hat sie aber die absolute Mehrheit verpasst und braucht einen Koalitionspartner. Es zeichnet sich eine schwierige Regierungsbildung ab.<\/p>\n<p class=\"text small\">Schwierigster Punkt dabei ist die Ann\u00e4herung an EU und NATO &#8211; ein NATO-Beitritt ist f\u00fcr den n\u00e4chsten Jahr geplant. Die Partei &#8220;Die Demokratische Front&#8221; ist mit rund 20% die zweitst\u00e4rkste Kraft geworden. Sie ist strikt gegen den NATO-Beitritt. Die Partei &#8220;Schl\u00fcssel&#8221;, die auf gut 10% kam, ist pro-westlich orientiert.<\/p>\n<p class=\"text small\">Dazu kommen mehrere kleinere Parteien, die wichtig werden k\u00f6nnten. Rein theoretisch k\u00f6nnten die Oppositionsparteien miteinander gegen die Regierungspartei koalieren. Doch das ist unwahrscheinlich, da die Opposition untereinander zerstritten ist.<\/p>\n<p class=\"text small\">Davon profitiert Djukanovic, der mit Unterbrechungen seit 25 Jahren an der Macht ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer wieder sonntags\u2026. Diesmal haben die Wahl News einen Schwerpunkt auf Osteuropa. In Tschechien wurde am Wochenende in der zweiten Runde der Senat gew\u00e4hlt. \u00a0In Montenegro hat die Partei des Regierungschefs\u00a0Milo Djukanovic die Parlamentswahl gewonnen, aber die absolute Mehrheit verpasst.<\/p>\n","protected":false},"author":267,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ub_ctt_via":"","spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[8],"tags":[260,90,317],"featured_image_src":null,"author_info":{"display_name":"Laila Oudray","author_link":"https:\/\/www.polyas.de\/blog\/author\/l-oudray"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS<\/title>\n<meta name=\"description\" content=\"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS\" \/>\n<meta property=\"og:description\" content=\"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen\" \/>\n<meta property=\"og:site_name\" content=\"POLYAS\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-17T10:55:03+00:00\" \/>\n<meta name=\"author\" content=\"Laila Oudray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laila Oudray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen\",\"url\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen\",\"name\":\"Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS\",\"isPartOf\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/#website\"},\"datePublished\":\"2016-10-17T10:55:03+00:00\",\"dateModified\":\"2016-10-17T10:55:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/3a108e5248b3998c0219f9ff4406ba8a\"},\"description\":\"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.polyas.de\/blog\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tschechien und Montenegro: Wahlsieger mit Verlusten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#website\",\"url\":\"https:\/\/www.polyas.de\/blog\/\",\"name\":\"POLYAS\",\"description\":\"the blog for secure online voting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.polyas.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/3a108e5248b3998c0219f9ff4406ba8a\",\"name\":\"Laila Oudray\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/494f68c63930bd25d02b8df8a6dbded8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/494f68c63930bd25d02b8df8a6dbded8?s=96&d=mm&r=g\",\"caption\":\"Laila Oudray\"},\"description\":\"Um die Welt zu gestalten und zu verbessern, ben\u00f6tigt man Informationen. Ich habe es mir zur Aufgabe gemacht, diese Informationen zu recherchieren und hoffentlich unterhaltsam aufzubereiten. Wenn ich nicht gerade das World Wide Web f\u00fcr die interessantesten Themen durchforste, lebe ich meine musikalische Seite aus und singe (wie man mir sagt, auch gar nicht so schlecht). Seit April arbeite ich bei Polyas. Hier bin ich f\u00fcr die Pressearbeit zust\u00e4ndig und schreibe Blogartikel.\",\"sameAs\":[\"http:\/\/www.polyas.de\"],\"url\":\"https:\/\/www.polyas.de\/blog\/author\/l-oudray\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS","description":"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen","og_locale":"de_DE","og_type":"article","og_title":"Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS","og_description":"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.","og_url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen","og_site_name":"POLYAS","article_published_time":"2016-10-17T10:55:03+00:00","author":"Laila Oudray","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Laila Oudray","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen","url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen","name":"Tschechien und Montenegro: Wahlsieger mit Verlusten - POLYAS","isPartOf":{"@id":"https:\/\/www.polyas.de\/blog\/#website"},"datePublished":"2016-10-17T10:55:03+00:00","dateModified":"2016-10-17T10:55:03+00:00","author":{"@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/3a108e5248b3998c0219f9ff4406ba8a"},"description":"In Tschechien und Montenegro wurde am Wochenende gew\u00e4hlt. Die Wahlsieger in beiden L\u00e4ndern m\u00fcssen Wahlverluste verkraften.","breadcrumb":{"@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechien-montenegro-wahlen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.polyas.de\/blog\/de"},{"@type":"ListItem","position":2,"name":"Tschechien und Montenegro: Wahlsieger mit Verlusten"}]},{"@type":"WebSite","@id":"https:\/\/www.polyas.de\/blog\/#website","url":"https:\/\/www.polyas.de\/blog\/","name":"POLYAS","description":"the blog for secure online voting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polyas.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/3a108e5248b3998c0219f9ff4406ba8a","name":"Laila Oudray","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.polyas.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/494f68c63930bd25d02b8df8a6dbded8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/494f68c63930bd25d02b8df8a6dbded8?s=96&d=mm&r=g","caption":"Laila Oudray"},"description":"Um die Welt zu gestalten und zu verbessern, ben\u00f6tigt man Informationen. Ich habe es mir zur Aufgabe gemacht, diese Informationen zu recherchieren und hoffentlich unterhaltsam aufzubereiten. Wenn ich nicht gerade das World Wide Web f\u00fcr die interessantesten Themen durchforste, lebe ich meine musikalische Seite aus und singe (wie man mir sagt, auch gar nicht so schlecht). Seit April arbeite ich bei Polyas. Hier bin ich f\u00fcr die Pressearbeit zust\u00e4ndig und schreibe Blogartikel.","sameAs":["http:\/\/www.polyas.de"],"url":"https:\/\/www.polyas.de\/blog\/author\/l-oudray"}]}},"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p72Pnr-Ug","jetpack-related-posts":[{"id":6223,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/tschechiens-praesidentschaftswahl","url_meta":{"origin":3488,"position":0},"title":"Tschechiens Pr\u00e4sidentschaftswahl 2018: Zeman muss in die Stichwahl","date":"15\/01\/2018","format":false,"excerpt":"Tschechiens Pr\u00e4sidentschaftswahl 2018 hat f\u00fcr keine \u00dcberraschungen gesorgt: Die erste Runde hat Amtsinhaber Milo\u0161 Zeman gewonnen, er muss aber in zwei Wochen in die Stichwahl. Sein Konkurrent ist der parteilose Chemieprofessor Ji\u0159\u00ed Draho\u0161. Alles zur Wahl wie immer in unseren #WahlNews. Zeman gewinnt Tschechiens Pr\u00e4sidentschaftswahl 2018 Es war die erste\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Erfahren Sie alles Aktuelle \u00fcber die Parlamentswahl in der Ukraine","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2016\/12\/Wahl-News-Schmal_810x280.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6694,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/parlamentswahl-slowenien","url_meta":{"origin":3488,"position":1},"title":"Slowenien: Schwierige Regierungsbildung zwischen Alpen und Adria","date":"04\/06\/2018","format":false,"excerpt":"Bei der Wahl zum Parlament in Slowenien hat die einwanderungsfeindliche Partei SDS von Ex-Ministerpr\u00e4sident Janez Jansa die meisten Stimmen bekommen. Eine Regierungsbildung wird wohl trotzdem schwierig werden, denn das linke Lager h\u00e4tte ebenso die M\u00f6glichkeit zu regieren. #WahlNews Der rechtskonservative Oppositionsf\u00fchrer hat die meisten Stimmen bei der Wahl in Slowenien\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Erfahren Sie alles Aktuelle \u00fcber die Parlamentswahl in der Ukraine","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2016\/12\/Wahl-News-Schmal_810x280.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5881,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/parlamentswahl-island","url_meta":{"origin":3488,"position":2},"title":"Wahl in Island: Acht Parteien ziehen ins Parlament ein","date":"30\/10\/2017","format":false,"excerpt":"In\u00a0Island wurde diesen Sonntag ein neues Parlament gew\u00e4hlt. Die Regierungsbildung wird schwierig, denn acht Parteien haben es ins Parlament geschafft. Aller Ergebnisse in unseren #WahlNews. Unabh\u00e4ngigkeitspartei bleibt st\u00e4rkste Kraft Nach der Parlamentswahl in Island bleibt die konservative Unabh\u00e4ngigkeitspartei des bisherigen Regierungschefs Bjarni Benediktsson trotz Stimmverlusten st\u00e4rkste Kraft. Sie holte rund\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Erfahren Sie alles Aktuelle \u00fcber die Parlamentswahl in der Ukraine","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2016\/12\/Wahl-News-Schmal_810x280.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5855,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/parlamentswahl-tschechien","url_meta":{"origin":3488,"position":3},"title":"Tschechien: Milliard\u00e4r Andrej Babis gewinnt Parlamentswahl","date":"23\/10\/2017","format":false,"excerpt":"Immer wieder sonntags\u2026 Am Wochenende wurde in gleich zwei osteurop\u00e4ischen L\u00e4ndern gew\u00e4hlt: In Tschechien ging es um eine neue Regierung, in Slowenien um die Pr\u00e4sidentschaftswahl. Wer gewonnen hat erfahren Sie in unseren #WahlNews. Gro\u00dfe Ver\u00e4nderungen in Tschechien Bei der Parlamentswahl in Tschechien gewann die rechtspopulistische ANO. Ihr Anf\u00fchrer, der Milliard\u00e4r\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Erfahren Sie alles Aktuelle \u00fcber die Parlamentswahl in der Ukraine","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2016\/12\/Wahl-News-Schmal_810x280.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6088,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/superwahljahr-2017-europa","url_meta":{"origin":3488,"position":4},"title":"R\u00fcckblick 2017: So hat das Superwahljahr Europa ver\u00e4ndert","date":"13\/12\/2017","format":false,"excerpt":"Mit dem Jahr 2017 endet f\u00fcr Europa ein Superwahljahr. Neben Gro\u00dfbritannien, Frankreich und Deutschland haben auch weitere EU-L\u00e4nder wie \u00d6sterreich oder die Niederlande neue\u00a0Parlamente gew\u00e4hlt. Doch was\u00a0haben diese Wahlen f\u00fcr Europa bedeutet? Superwahljahr ist seltener Zufall So etwas passiert nicht alle Jahre: Drei der einwohnerst\u00e4rksten EU-Staaten w\u00e4hlen im selben Jahr.\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Das Superwahljahr 2017 hielt f\u00fcr Europa einige \u00dcberraschungen bereit.","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2017\/12\/world-1264062_1920.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3790,"url":"https:\/\/www.polyas.de\/blog\/de\/online-wahlen\/parlamentswahl-rumaenien-mazedonien","url_meta":{"origin":3488,"position":5},"title":"Ein klarer Sieger und eine schwierige Regierungsbildung","date":"12\/12\/2016","format":false,"excerpt":"Immer wieder sonntags...\u00a0Am 11.12.2016 w\u00e4hlten die B\u00fcrger\u00a0in Mazedonien und Rum\u00e4nien ihr Parlament. Da der Wahlkampf von einigen Skandalen \u00fcberschattet wurde, fanden die Wahlen unter den wachsamen Augen internationaler Beobachter statt. Die Ereignisse im \u00dcberblick Mazedonien: In der ex-jugoslawischen Republik hat nach Ausz\u00e4hlung von 85% der Stimmen die rechtskonservative Regierungspartei VMRO-DPMNE\u2026","rel":"","context":"In &quot;Wahl News&quot;","img":{"alt_text":"Alle Infos zu Parlamentswahlen, Pr\u00e4sidentschaftswahlen und sonstigen Wahlen rund um die Welt: in unseren #WahlNews","src":"https:\/\/i0.wp.com\/www.polyas.de\/blog\/wp-content\/uploads\/2017\/01\/Wahl-News-Schmal_810x280.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/3488"}],"collection":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/users\/267"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/comments?post=3488"}],"version-history":[{"count":1,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/3488\/revisions"}],"predecessor-version":[{"id":3489,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/posts\/3488\/revisions\/3489"}],"wp:attachment":[{"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/media?parent=3488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/categories?post=3488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polyas.de\/blog\/wp-json\/wp\/v2\/tags?post=3488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}